{"id":215,"count":4,"description":"","link":"https:\/\/www.maldotravels.com\/es\/tag\/full-day-tour\/","name":"Tour de d\u00eda completo","slug":"full-day-tour","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.maldotravels.com\/es\/wp-json\/wp\/v2\/tags\/215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maldotravels.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.maldotravels.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.maldotravels.com\/es\/wp-json\/wp\/v2\/posts?tags=215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}